{"id":43119,"date":"2021-04-07T18:30:24","date_gmt":"2021-04-07T16:30:24","guid":{"rendered":"https:\/\/izimi.yaqa.be\/ufaq\/combien-de-temps-les-donnees-que-jai-placees-dans-mon-coffre-fort-seront-elles-conservees\/"},"modified":"2023-04-12T22:38:59","modified_gmt":"2023-04-12T20:38:59","slug":"combien-de-temps-les-donnees-que-jai-placees-dans-mon-coffre-fort-seront-elles-conservees","status":"publish","type":"ufaq","link":"https:\/\/izimi.yaqa.be\/fr\/faqs\/combien-de-temps-les-donnees-que-jai-placees-dans-mon-coffre-fort-seront-elles-conservees\/","title":{"rendered":"Combien de temps les donn\u00e9es que j\u2019ai plac\u00e9es dans mon coffre-fort seront-elles conserv\u00e9es ?"},"content":{"rendered":"<style>.ewd-ufaq-faq-display-style-block.ewd-ufaq-post-active, .ewd-ufaq-faq-display-style-block.ewd-ufaq-post-active a,.ewd-ufaq-faq-display-style-block:hover, .ewd-ufaq-faq-display-style-block:hover a, .ewd-ufaq-faq-display-style-block:hover h1 { background-color: #ffffff !important; }.ewd-ufaq-faq-display-style-border_block.ewd-ufaq-post-active, .ewd-ufaq-faq-display-style-border_block:hover, .ewd-ufaq-faq-display-style-border_block:hover h1 { background-color: #ffffff !important; }.ewd-ufaq-faq-display-style-border_block .ewd-ufaq-faq-body { border-color: #ffffff !important; }.ewd-ufaq-faq-display-style-border_block .comment-reply-title, .ewd-ufaq-faq-display-style-border_block:hover .comment-reply-title { background-color: transparent !important; }div.ewd-ufaq-faq-category-title h3 { font-size: 1.2em !important; }div.ewd-ufaq-faq-category-title h3 { color: #3d3836 !important; }div.ewd-ufaq-faq-categories, div.ewd-ufaq-faq-tags { padding: 10px 0px !important; }<\/style><div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-distinct ewd-ufaq-category-tabs- ewd-ufaq-faq-category-title-accordion\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='title' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='desc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/fr\/wp-json\/wp\/v2\/ufaq\/43119' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-default\" id='ewd-ufaq-post-43119-IYa80lmGw9' data-post_id='43119'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title '>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='https:\/\/izimi.yaqa.be\/fr\/faqs\/combien-de-temps-les-donnees-que-jai-placees-dans-mon-coffre-fort-seront-elles-conservees\/' >\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-'>\n\t\t\t<span >B<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h1>\n\t\t\t\tCombien de temps les donn\u00e9es que j\u2019ai plac\u00e9es dans mon coffre-fort seront-elles conserv\u00e9es ?\t\t\t<\/h1>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t<p>Pour autant que l\u2019utilisateur ne les supprime pas, ses donn\u00e9es et documents d\u00e9pos\u00e9s dans son coffre-fort sont conserv\u00e9s \u00e0 vie dans son coffre-fort. Apr\u00e8s le d\u00e9c\u00e8s de l\u2019utilisateur, les donn\u00e9es et documents sont conserv\u00e9s pour un maximum de 24 mois suppl\u00e9mentaires (<a href=\"https:\/\/izimi.yaqa.be\/conditions-dutilisation\/\">cf. article 13 des conditions d\u2019utilisation en vigueur pour plus d\u2019informations<\/a>).<\/p>\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-ratings'>\n\t\n\t<div class='ewd-ufaq-ratings-label'>\n\t\tDid you find this FAQ helpful?\t<\/div>\n\t\n\t<div class='ewd-ufaq-rating-button ewd-ufaq-up-vote ewd-ufaq-ratings-default-image' data-faq_id='43119'>\n\t\t<img decoding=\"async\" src=\"https:\/\/izimi.yaqa.be\/wp-content\/plugins\/ultimate-faqs\/assets\/img\/Thumbs-up-icon.png\" alt=\"Thumbs Up Icon\">\t\t<span>8<\/span>\n\t<\/div>\n\t\n\t<div class='ewd-ufaq-rating-button ewd-ufaq-down-vote ewd-ufaq-ratings-default-image' data-faq_id='43119'>\n\t\t<img decoding=\"async\" src=\"https:\/\/izimi.yaqa.be\/wp-content\/plugins\/ultimate-faqs\/assets\/img\/Thumbs-down-icon.png\" alt=\"Thumbs Down Icon\">\t\t<span>0<\/span>\n\t<\/div>\n<\/div>\n\n<div class='ewd-ufaq-clear'><\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>B Combien de temps les donn\u00e9es que j\u2019ai plac\u00e9es dans mon coffre-fort seront-elles conserv\u00e9es ? Pour autant que l\u2019utilisateur ne les supprime pas, ses donn\u00e9es et documents d\u00e9pos\u00e9s dans son coffre-fort sont conserv\u00e9s \u00e0 vie dans son coffre-fort. Apr\u00e8s le d\u00e9c\u00e8s de l\u2019utilisateur, les donn\u00e9es et documents sont conserv\u00e9s pour un maximum de 24 mois suppl\u00e9mentaires (cf. article 13 des &#8230; <\/p>\n<div><a href=\"https:\/\/izimi.yaqa.be\/fr\/faqs\/combien-de-temps-les-donnees-que-jai-placees-dans-mon-coffre-fort-seront-elles-conservees\/\" class=\"more-link\">Read More<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","ufaq-category":[39],"ufaq-tag":[],"_links":{"self":[{"href":"https:\/\/izimi.yaqa.be\/fr\/wp-json\/wp\/v2\/ufaq\/43119"}],"collection":[{"href":"https:\/\/izimi.yaqa.be\/fr\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/izimi.yaqa.be\/fr\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/izimi.yaqa.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/izimi.yaqa.be\/fr\/wp-json\/wp\/v2\/comments?post=43119"}],"wp:attachment":[{"href":"https:\/\/izimi.yaqa.be\/fr\/wp-json\/wp\/v2\/media?parent=43119"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/izimi.yaqa.be\/fr\/wp-json\/wp\/v2\/ufaq-category?post=43119"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/izimi.yaqa.be\/fr\/wp-json\/wp\/v2\/ufaq-tag?post=43119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}